{"id":8018,"date":"2023-11-09T14:59:05","date_gmt":"2023-11-09T13:59:05","guid":{"rendered":"https:\/\/www.irriland.it\/?p=8018"},"modified":"2023-11-09T15:04:26","modified_gmt":"2023-11-09T14:04:26","slug":"gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente","status":"publish","type":"post","link":"https:\/\/www.irriland.it\/en\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/","title":{"rendered":"Gruppo elettrogeno: un alleato contro le interruzioni di corrente"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">I <\/span><a href=\"https:\/\/www.irriland.it\/project\/gruppi-elettrogeni\/\"><b>gruppi elettrogeni<\/b><\/a><span style=\"font-weight: 400;\"> sono dispositivi che, grazie a un motore termico, convertono l&#8217;energia meccanica in energia elettrica. Possono rivelarsi estremamente utili nei casi in cui la rete elettrica \u00e8 carente o del tutto assente.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Per questa ragione vengono <\/span><b>impiegati in tutti i contesti<\/b><span style=\"font-weight: 400;\"> in cui \u00e8 importante garantire <\/span><b>continuit\u00e0 elettrica<\/b><span style=\"font-weight: 400;\">: dall\u2019irrigazione agricola al settore industriale, dai centri commerciali agli ospedali, dagli hotel agli uffici e molto altro. Ripristinando la corrente, infatti, consentono il normale svolgimento delle attivit\u00e0 anche in caso di imprevisti.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Per rispondere alle richieste sempre crescenti e venire incontro alle esigenze dei clienti, <\/span><b>Irriland <\/b><span style=\"font-weight: 400;\">ha arricchito la sua gamma di prodotti con<\/span><b> i <\/b><b>gruppi elettrogeni<\/b><b>.<\/b><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Caratteristiche dei gruppi elettrogeni Irriland<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">La linea di <\/span><a href=\"https:\/\/www.irriland.it\/prodotti\/gruppi-elettrogeni-motopompe\/\"><span style=\"font-weight: 400;\">gruppi elettrogeni Irriland<\/span><\/a><span style=\"font-weight: 400;\"> \u00e8 pensata per rispondere a svariate esigenze. I modelli sono estremamente versatili e garantiscono una gamma che varia<\/span><b> dai 5 ai 2000 kVA <\/b><span style=\"font-weight: 400;\">di potenza elettrica apparente. Vengono collaudati in sala prove da tecnici specializzati, i quali effettuano test sotto carico per verificare le funzionalit\u00e0 e assicurare <\/span><b>il massimo dell\u2019affidabilit\u00e0 e dell\u2019efficienza.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Ogni gruppo elettrogeno \u00e8 alimentato da un motore<\/span> <span style=\"font-weight: 400;\">di ultima generazione, in grado di garantire prestazioni eccellenti con un<\/span><b> basso impatto ambientale.<\/b><span style=\"font-weight: 400;\"> Dispone anche di un quadro di comando estremamente intuitivo, che garantisce<\/span><b> facilit\u00e0 di utilizzo<\/b><span style=\"font-weight: 400;\"> in qualsiasi condizione e situazione, anche agli operatori meno esperti.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Diverse opzioni di personalizzazione<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Per venire incontro a diverse necessit\u00e0, Irriland personalizza i gruppi elettrogeni in base alle richieste, per adattarli a <\/span><b>qualsiasi tipo di impiego.<\/b><span style=\"font-weight: 400;\"> Il cliente pu\u00f2 scegliere il tipo di alimentazione del motore e il quadro di comando, pu\u00f2 optare tra gruppo elettrogeno aperto o insonorizzato.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">In questo caso, il dispositivo viene dotato di una cofanatura in acciaio pressopiegato rivestito con materiale fonoassorbente, realizzata secondo le norme ISO. Tra le varie opzioni, \u00e8 possibile scegliere anche tra gruppo elettrogeno verniciato o zincato. <\/span><b>La zincatura \u00e8 una particolarit\u00e0 della gamma Irriland<\/b><span style=\"font-weight: 400;\"> ed \u00e8 molto indicata in caso di uso all\u2019aperto, poich\u00e9 protegge la macchina dagli agenti atmosferici.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>La zincatura: cos\u2019\u00e8 e quali sono i vantaggi<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">La <\/span><b>zincatura<\/b><span style=\"font-weight: 400;\"> \u00e8 un processo di <\/span><b>protezione <\/b><span style=\"font-weight: 400;\">che consiste nell&#8217;applicazione di uno<\/span><b> strato di zinco<\/b><span style=\"font-weight: 400;\"> sulla superficie metallica della macchina. Questa particolare lavorazione ha diversi vantaggi.<\/span><\/p>\n<h3><b>1. Maggiore durabilit\u00e0<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Il rivestimento in zinco protegge dai raggi UV, dall\u2019acqua e da altre sostanze aggressive grazie alla sua <\/span><b>funzione anticorrosiva.<\/b><span style=\"font-weight: 400;\"> In questo modo la vita utile del gruppo elettrogeno si prolunga e i costi legati al rinnovo delle attrezzature si riducono. Possono infatti passare anche decine di anni prima della sostituzione.<\/span><\/p>\n<h3><b>2. Bassa manutenzione<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">All\u2019interno della macchina si creano condizioni di temperatura e umidit\u00e0 particolari che, a lungo andare, possono provocare danni irreversibili. La zincatura<\/span><b> impedisce lo sviluppo della ruggine<\/b><span style=\"font-weight: 400;\"> ed evita che eventuali graffi o abrasioni compromettano l\u2019efficienza del gruppo elettrogeno.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La lega ferro-zinco che riveste l\u2019acciaio, infatti, <\/span><b>protegge anche le parti interne<\/b><span style=\"font-weight: 400;\"> e riduce il numero di interventi manutentivi necessari a preservare le funzionalit\u00e0 della macchina.<\/span><\/p>\n<h3><b>3. Sostenibilit\u00e0<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">La zincatura \u00e8 un processo che non impiega sostanze chimiche nocive e non disperde alcun materiale nell\u2019ambiente. Al termine dell\u2019utilizzo,<\/span><b> i materiali possono essere riutilizzati<\/b><span style=\"font-weight: 400;\"> per altri impieghi, per esempio per la costruzione di edifici e altre strutture. Inoltre, acciaio e zinco possono essere <\/span><b>completamente riciclati <\/b><span style=\"font-weight: 400;\">senza perdere le proprie caratteristiche.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c8 dunque una lavorazione che incentiva l\u2019economia circolare e la riduzione degli sprechi. Un processo virtuoso, che rende le attivit\u00e0 di irrigazione agricola<\/span><b> pi\u00f9 efficienti e pi\u00f9 sostenibili.<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I gruppi elettrogeni sono dispositivi che, grazie a un motore termico, convertono l&#8217;energia meccanica in energia elettrica. Possono rivelarsi estremamente utili nei casi in cui la rete elettrica \u00e8 carente o del tutto assente.\u00a0 Per questa ragione vengono impiegati in tutti i contesti in cui \u00e8 importante garantire continuit\u00e0 elettrica: dall\u2019irrigazione agricola al settore industriale,&hellip;<\/p>\n","protected":false},"author":3,"featured_media":8019,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-1","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gruppo elettrogeno: un alleato contro le interruzioni di corrente | IRRILAND<\/title>\n<meta name=\"description\" content=\"I gruppi elettrogeni sono dispositivi che, grazie a un motore termico, convertono l&#039;energia meccanica in energia elettrica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gruppo elettrogeno: un alleato contro le interruzioni di corrente | IRRILAND\" \/>\n<meta property=\"og:description\" content=\"I gruppi elettrogeni sono dispositivi che, grazie a un motore termico, convertono l&#039;energia meccanica in energia elettrica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/\" \/>\n<meta property=\"og:site_name\" content=\"IRRILAND\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-09T13:59:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-09T14:04:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irriland.it\/wp-content\/uploads\/2023\/11\/gruppo-elettrogeno.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Massimo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Massimo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/\"},\"author\":{\"name\":\"Massimo\",\"@id\":\"https:\/\/www.irriland.it\/#\/schema\/person\/f07554b449dfa41a873c1be54a90f775\"},\"headline\":\"Gruppo elettrogeno: un alleato contro le interruzioni di corrente\",\"datePublished\":\"2023-11-09T13:59:05+00:00\",\"dateModified\":\"2023-11-09T14:04:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/\"},\"wordCount\":570,\"publisher\":{\"@id\":\"https:\/\/www.irriland.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irriland.it\/wp-content\/uploads\/2023\/11\/gruppo-elettrogeno.webp\",\"articleSection\":[\"NEWS\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/\",\"url\":\"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/\",\"name\":\"Gruppo elettrogeno: un alleato contro le interruzioni di corrente | IRRILAND\",\"isPartOf\":{\"@id\":\"https:\/\/www.irriland.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irriland.it\/wp-content\/uploads\/2023\/11\/gruppo-elettrogeno.webp\",\"datePublished\":\"2023-11-09T13:59:05+00:00\",\"dateModified\":\"2023-11-09T14:04:26+00:00\",\"description\":\"I gruppi elettrogeni sono dispositivi che, grazie a un motore termico, convertono l'energia meccanica in energia elettrica.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/#primaryimage\",\"url\":\"https:\/\/www.irriland.it\/wp-content\/uploads\/2023\/11\/gruppo-elettrogeno.webp\",\"contentUrl\":\"https:\/\/www.irriland.it\/wp-content\/uploads\/2023\/11\/gruppo-elettrogeno.webp\",\"width\":840,\"height\":420,\"caption\":\"Grupp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.irriland.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gruppo elettrogeno: un alleato contro le interruzioni di corrente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irriland.it\/#website\",\"url\":\"https:\/\/www.irriland.it\/\",\"name\":\"IRRILAND\",\"description\":\"Generatori al cardano, pivot e sistemi lineari\",\"publisher\":{\"@id\":\"https:\/\/www.irriland.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irriland.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.irriland.it\/#organization\",\"name\":\"Irriland srl\",\"url\":\"https:\/\/www.irriland.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.irriland.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.irriland.it\/wp-content\/uploads\/2020\/10\/hd.png\",\"contentUrl\":\"https:\/\/www.irriland.it\/wp-content\/uploads\/2020\/10\/hd.png\",\"width\":362,\"height\":200,\"caption\":\"Irriland srl\"},\"image\":{\"@id\":\"https:\/\/www.irriland.it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.irriland.it\/#\/schema\/person\/f07554b449dfa41a873c1be54a90f775\",\"name\":\"Massimo\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gruppo elettrogeno: un alleato contro le interruzioni di corrente | IRRILAND","description":"I gruppi elettrogeni sono dispositivi che, grazie a un motore termico, convertono l'energia meccanica in energia elettrica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/","og_locale":"en_US","og_type":"article","og_title":"Gruppo elettrogeno: un alleato contro le interruzioni di corrente | IRRILAND","og_description":"I gruppi elettrogeni sono dispositivi che, grazie a un motore termico, convertono l'energia meccanica in energia elettrica.","og_url":"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/","og_site_name":"IRRILAND","article_published_time":"2023-11-09T13:59:05+00:00","article_modified_time":"2023-11-09T14:04:26+00:00","og_image":[{"width":840,"height":420,"url":"https:\/\/www.irriland.it\/wp-content\/uploads\/2023\/11\/gruppo-elettrogeno.webp","type":"image\/webp"}],"author":"Massimo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Massimo","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/#article","isPartOf":{"@id":"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/"},"author":{"name":"Massimo","@id":"https:\/\/www.irriland.it\/#\/schema\/person\/f07554b449dfa41a873c1be54a90f775"},"headline":"Gruppo elettrogeno: un alleato contro le interruzioni di corrente","datePublished":"2023-11-09T13:59:05+00:00","dateModified":"2023-11-09T14:04:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/"},"wordCount":570,"publisher":{"@id":"https:\/\/www.irriland.it\/#organization"},"image":{"@id":"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irriland.it\/wp-content\/uploads\/2023\/11\/gruppo-elettrogeno.webp","articleSection":["NEWS"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/","url":"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/","name":"Gruppo elettrogeno: un alleato contro le interruzioni di corrente | IRRILAND","isPartOf":{"@id":"https:\/\/www.irriland.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/#primaryimage"},"image":{"@id":"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irriland.it\/wp-content\/uploads\/2023\/11\/gruppo-elettrogeno.webp","datePublished":"2023-11-09T13:59:05+00:00","dateModified":"2023-11-09T14:04:26+00:00","description":"I gruppi elettrogeni sono dispositivi che, grazie a un motore termico, convertono l'energia meccanica in energia elettrica.","breadcrumb":{"@id":"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/#primaryimage","url":"https:\/\/www.irriland.it\/wp-content\/uploads\/2023\/11\/gruppo-elettrogeno.webp","contentUrl":"https:\/\/www.irriland.it\/wp-content\/uploads\/2023\/11\/gruppo-elettrogeno.webp","width":840,"height":420,"caption":"Grupp"},{"@type":"BreadcrumbList","@id":"https:\/\/www.irriland.it\/gruppo-elettrogeno-un-alleato-contro-le-interruzioni-di-corrente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irriland.it\/en\/"},{"@type":"ListItem","position":2,"name":"Gruppo elettrogeno: un alleato contro le interruzioni di corrente"}]},{"@type":"WebSite","@id":"https:\/\/www.irriland.it\/#website","url":"https:\/\/www.irriland.it\/","name":"IRRILAND","description":"Generatori al cardano, pivot e sistemi lineari","publisher":{"@id":"https:\/\/www.irriland.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irriland.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.irriland.it\/#organization","name":"Irriland srl","url":"https:\/\/www.irriland.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.irriland.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.irriland.it\/wp-content\/uploads\/2020\/10\/hd.png","contentUrl":"https:\/\/www.irriland.it\/wp-content\/uploads\/2020\/10\/hd.png","width":362,"height":200,"caption":"Irriland srl"},"image":{"@id":"https:\/\/www.irriland.it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.irriland.it\/#\/schema\/person\/f07554b449dfa41a873c1be54a90f775","name":"Massimo"}]}},"_links":{"self":[{"href":"https:\/\/www.irriland.it\/en\/wp-json\/wp\/v2\/posts\/8018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irriland.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irriland.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irriland.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irriland.it\/en\/wp-json\/wp\/v2\/comments?post=8018"}],"version-history":[{"count":0,"href":"https:\/\/www.irriland.it\/en\/wp-json\/wp\/v2\/posts\/8018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irriland.it\/en\/wp-json\/wp\/v2\/media\/8019"}],"wp:attachment":[{"href":"https:\/\/www.irriland.it\/en\/wp-json\/wp\/v2\/media?parent=8018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irriland.it\/en\/wp-json\/wp\/v2\/categories?post=8018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irriland.it\/en\/wp-json\/wp\/v2\/tags?post=8018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}